{"id":1957,"date":"2011-08-27T23:30:07","date_gmt":"2011-08-28T04:00:07","guid":{"rendered":"https:\/\/tucuatro.com\/camburpinton\/?p=1957"},"modified":"2011-08-27T23:30:07","modified_gmt":"2011-08-28T04:00:07","slug":"3-consejos-para-cuidar-tu-cuatro","status":"publish","type":"post","link":"https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/","title":{"rendered":"3 consejos para cuidar tu cuatro"},"content":{"rendered":"<p style=\"text-align: justify\">Cualquier venezolano sabe que uno de los bienes m\u00e1s preciados a nivel cultural que puede haber en una casa es el Cuatro Venezolano. \u00a0No en vano todas las familias venezolanas procuran tener uno, especialmente las familias que se encuentran viviendo fuera del pa\u00eds.<\/p>\n<p style=\"text-align: justify\">M\u00e1s aun, los cuatristas saben el valor adicional aque tiene un cuatro. \u00a0Es m\u00e1s que un simple instrumento. Es un compa\u00f1ero, un aliado fiel.<!--more--><\/p>\n<p style=\"text-align: justify\">Aqu\u00ed tienes 3 consejos para que tu cuatro te dure una eternidad.<\/p>\n<h2 style=\"text-align: justify\">Limpiar los trastes a menudo<\/h2>\n<p style=\"text-align: justify\">Lo uses frecuentemente o no, el cuatro acumula polvo y suciedad entre los trastes, especificamente a los lados de cada palito de metal. \u00a0L\u00edmpialos cuidadosamente con un objeto punteagudo para remover toda suciedad. \u00a0Trata de no darle muy duro porque puedes rallarlo.<\/p>\n<h2 style=\"text-align: justify\">Guardarlo en un lugar seco y fresco<\/h2>\n<p>No hay nada que le haga m\u00e1s da\u00f1o a la madera que la humedad y el calor. \u00a0Trata de tener tu cuatro en un rinc\u00f3n seco y donde no le pegue el sol directamente. \u00a0Ni hablar de ponerlo en un balc\u00f3n o en el patio. \u00a0 All\u00ed s\u00f3lo lograr\u00e1s que se da\u00f1e m\u00e1s r\u00e1pidamente.<\/p>\n<h2 style=\"text-align: justify\">Cambiar las cuerdas cada 8 a 10 meses<\/h2>\n<p>As\u00ed no lo toques muy a menudo, las tensi\u00f3n natural que tienen las cuerdas hace que estas se desgasten r\u00e1pidamente. \u00a0Un cuatro con las cuerdas viejas tiende a sonar agudo y emitir unas frecuencias desagradables. \u00a0 Si lo usas frecuentemente, trata de cambiarlas con regularidad, por lo menos cada 6 meses. \u00a0Si no lo usas puedes cambiarselas cada 8 \u00a0o 10 meses, sea lo que sea, igual procura cambiarle sus cuerdas antes que se acabe el a\u00f1o.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify\">Cualquier venezolano sabe que uno de los bienes m\u00e1s preciados a nivel cultural que puede haber en una casa es el Cuatro Venezolano. \u00a0No en vano todas las familias venezolanas procuran tener uno, especialmente las familias que se encuentran viviendo fuera del pa\u00eds.<\/p>\n<p style=\"text-align: justify\">M\u00e1s aun, los cuatristas saben el valor adicional<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","_tucuatro_chord_instrument":""},"categories":[2],"tags":[11],"class_list":["post-1957","post","type-post","status-publish","format-standard","hentry","category-cuatro","tag-cuatro-venezolano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 consejos para cuidar tu cuatro - CamburPinton<\/title>\n<meta name=\"description\" content=\"Cualquier venezolano sabe que uno de los bienes m\u00e1s preciados a nivel cultural que puede haber en una casa es el Cuatro Venezolano. \u00a0No en vano todas las familias venezolanas procuran tener uno, especialmente las familias que se encuentran viviendo fuera del pa\u00eds. M\u00e1s aun, los cuatristas saben el valor adicional\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 consejos para cuidar tu cuatro - CamburPinton\" \/>\n<meta property=\"og:description\" content=\"Cualquier venezolano sabe que uno de los bienes m\u00e1s preciados a nivel cultural que puede haber en una casa es el Cuatro Venezolano. \u00a0No en vano todas las familias venezolanas procuran tener uno, especialmente las familias que se encuentran viviendo fuera del pa\u00eds. M\u00e1s aun, los cuatristas saben el valor adicional\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/\" \/>\n<meta property=\"og:site_name\" content=\"CamburPinton\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-28T04:00:07+00:00\" \/>\n<meta name=\"author\" content=\"Adrian Toro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adrian Toro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/3-consejos-para-cuidar-tu-cuatro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/3-consejos-para-cuidar-tu-cuatro\\\/\"},\"author\":{\"name\":\"Adrian Toro\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#\\\/schema\\\/person\\\/182f36d7f076c0e15716be890bb6d074\"},\"headline\":\"3 consejos para cuidar tu cuatro\",\"datePublished\":\"2011-08-28T04:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/3-consejos-para-cuidar-tu-cuatro\\\/\"},\"wordCount\":288,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#organization\"},\"keywords\":[\"cuatro venezolano\"],\"articleSection\":[\"Cuatro Instrumento Musical\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/3-consejos-para-cuidar-tu-cuatro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/3-consejos-para-cuidar-tu-cuatro\\\/\",\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/3-consejos-para-cuidar-tu-cuatro\\\/\",\"name\":\"3 consejos para cuidar tu cuatro - CamburPinton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#website\"},\"datePublished\":\"2011-08-28T04:00:07+00:00\",\"description\":\"Cualquier venezolano sabe que uno de los bienes m\u00e1s preciados a nivel cultural que puede haber en una casa es el Cuatro Venezolano. \u00a0No en vano todas las familias venezolanas procuran tener uno, especialmente las familias que se encuentran viviendo fuera del pa\u00eds. M\u00e1s aun, los cuatristas saben el valor adicional\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/3-consejos-para-cuidar-tu-cuatro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/3-consejos-para-cuidar-tu-cuatro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/3-consejos-para-cuidar-tu-cuatro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3 consejos para cuidar tu cuatro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#website\",\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/\",\"name\":\"CamburPinton\",\"description\":\"El blog del Cuatro Venezolano, por TuCuatro\",\"publisher\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#organization\",\"name\":\"CamburPinton\",\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2020\\\/02\\\/fretboard_icon_black-64px.png\",\"contentUrl\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2020\\\/02\\\/fretboard_icon_black-64px.png\",\"width\":64,\"height\":107,\"caption\":\"CamburPinton\"},\"image\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#\\\/schema\\\/person\\\/182f36d7f076c0e15716be890bb6d074\",\"name\":\"Adrian Toro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lh3.googleusercontent.com\\\/a\\\/ACg8ocLwLCmGuaPjDUjycH1soWxJ2CWxtdwwxTMhw7SjMADBmZbcikz5ww=s96-c?sz=50\",\"url\":\"https:\\\/\\\/lh3.googleusercontent.com\\\/a\\\/ACg8ocLwLCmGuaPjDUjycH1soWxJ2CWxtdwwxTMhw7SjMADBmZbcikz5ww=s96-c?sz=50\",\"contentUrl\":\"https:\\\/\\\/lh3.googleusercontent.com\\\/a\\\/ACg8ocLwLCmGuaPjDUjycH1soWxJ2CWxtdwwxTMhw7SjMADBmZbcikz5ww=s96-c?sz=50\",\"caption\":\"Adrian Toro\"},\"description\":\"Adri\u00e1n Toro es el fundador de TuCuatro Corp., una empresa dedicada a la difusi\u00f3n y ense\u00f1anza de instrumentos folkl\u00f3ricos, con un enfoque especial en el cuatro venezolano. Apasionado por la m\u00fasica y la educaci\u00f3n, ha trabajado durante a\u00f1os para conectar a m\u00fasicos, estudiantes y aficionados con recursos innovadores para aprender y perfeccionar su t\u00e9cnica. Bajo su liderazgo, TuCuatro se ha convertido en una plataforma de referencia internacional, promoviendo la riqueza cultural de los instrumentos de cuerda ex\u00f3ticos. Su misi\u00f3n es garantizar que estas tradiciones musicales sigan vivas y accesibles para futuras generaciones.\",\"sameAs\":[\"https:\\\/\\\/tucuatro.com\"],\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/author\\\/adrianifero\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 consejos para cuidar tu cuatro - CamburPinton","description":"Cualquier venezolano sabe que uno de los bienes m\u00e1s preciados a nivel cultural que puede haber en una casa es el Cuatro Venezolano. \u00a0No en vano todas las familias venezolanas procuran tener uno, especialmente las familias que se encuentran viviendo fuera del pa\u00eds. M\u00e1s aun, los cuatristas saben el valor adicional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/","og_locale":"es_ES","og_type":"article","og_title":"3 consejos para cuidar tu cuatro - CamburPinton","og_description":"Cualquier venezolano sabe que uno de los bienes m\u00e1s preciados a nivel cultural que puede haber en una casa es el Cuatro Venezolano. \u00a0No en vano todas las familias venezolanas procuran tener uno, especialmente las familias que se encuentran viviendo fuera del pa\u00eds. M\u00e1s aun, los cuatristas saben el valor adicional","og_url":"https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/","og_site_name":"CamburPinton","article_published_time":"2011-08-28T04:00:07+00:00","author":"Adrian Toro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Adrian Toro","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/#article","isPartOf":{"@id":"https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/"},"author":{"name":"Adrian Toro","@id":"https:\/\/tucuatro.com\/camburpinton\/#\/schema\/person\/182f36d7f076c0e15716be890bb6d074"},"headline":"3 consejos para cuidar tu cuatro","datePublished":"2011-08-28T04:00:07+00:00","mainEntityOfPage":{"@id":"https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/"},"wordCount":288,"commentCount":3,"publisher":{"@id":"https:\/\/tucuatro.com\/camburpinton\/#organization"},"keywords":["cuatro venezolano"],"articleSection":["Cuatro Instrumento Musical"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/","url":"https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/","name":"3 consejos para cuidar tu cuatro - CamburPinton","isPartOf":{"@id":"https:\/\/tucuatro.com\/camburpinton\/#website"},"datePublished":"2011-08-28T04:00:07+00:00","description":"Cualquier venezolano sabe que uno de los bienes m\u00e1s preciados a nivel cultural que puede haber en una casa es el Cuatro Venezolano. \u00a0No en vano todas las familias venezolanas procuran tener uno, especialmente las familias que se encuentran viviendo fuera del pa\u00eds. M\u00e1s aun, los cuatristas saben el valor adicional","breadcrumb":{"@id":"https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tucuatro.com\/camburpinton\/3-consejos-para-cuidar-tu-cuatro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tucuatro.com\/camburpinton\/"},{"@type":"ListItem","position":2,"name":"3 consejos para cuidar tu cuatro"}]},{"@type":"WebSite","@id":"https:\/\/tucuatro.com\/camburpinton\/#website","url":"https:\/\/tucuatro.com\/camburpinton\/","name":"CamburPinton","description":"El blog del Cuatro Venezolano, por TuCuatro","publisher":{"@id":"https:\/\/tucuatro.com\/camburpinton\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tucuatro.com\/camburpinton\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tucuatro.com\/camburpinton\/#organization","name":"CamburPinton","url":"https:\/\/tucuatro.com\/camburpinton\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tucuatro.com\/camburpinton\/#\/schema\/logo\/image\/","url":"https:\/\/tucuatro.com\/camburpinton\/wp-content\/uploads\/sites\/5\/2020\/02\/fretboard_icon_black-64px.png","contentUrl":"https:\/\/tucuatro.com\/camburpinton\/wp-content\/uploads\/sites\/5\/2020\/02\/fretboard_icon_black-64px.png","width":64,"height":107,"caption":"CamburPinton"},"image":{"@id":"https:\/\/tucuatro.com\/camburpinton\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tucuatro.com\/camburpinton\/#\/schema\/person\/182f36d7f076c0e15716be890bb6d074","name":"Adrian Toro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLwLCmGuaPjDUjycH1soWxJ2CWxtdwwxTMhw7SjMADBmZbcikz5ww=s96-c?sz=50","url":"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLwLCmGuaPjDUjycH1soWxJ2CWxtdwwxTMhw7SjMADBmZbcikz5ww=s96-c?sz=50","contentUrl":"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLwLCmGuaPjDUjycH1soWxJ2CWxtdwwxTMhw7SjMADBmZbcikz5ww=s96-c?sz=50","caption":"Adrian Toro"},"description":"Adri\u00e1n Toro es el fundador de TuCuatro Corp., una empresa dedicada a la difusi\u00f3n y ense\u00f1anza de instrumentos folkl\u00f3ricos, con un enfoque especial en el cuatro venezolano. Apasionado por la m\u00fasica y la educaci\u00f3n, ha trabajado durante a\u00f1os para conectar a m\u00fasicos, estudiantes y aficionados con recursos innovadores para aprender y perfeccionar su t\u00e9cnica. Bajo su liderazgo, TuCuatro se ha convertido en una plataforma de referencia internacional, promoviendo la riqueza cultural de los instrumentos de cuerda ex\u00f3ticos. Su misi\u00f3n es garantizar que estas tradiciones musicales sigan vivas y accesibles para futuras generaciones.","sameAs":["https:\/\/tucuatro.com"],"url":"https:\/\/tucuatro.com\/camburpinton\/author\/adrianifero\/"}]}},"_links":{"self":[{"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/posts\/1957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/comments?post=1957"}],"version-history":[{"count":0,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/posts\/1957\/revisions"}],"wp:attachment":[{"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/media?parent=1957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/categories?post=1957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/tags?post=1957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}