{"id":4155,"date":"2012-11-24T08:21:11","date_gmt":"2012-11-24T12:51:11","guid":{"rendered":"https:\/\/tucuatro.com\/camburpinton\/?p=4155"},"modified":"2020-02-22T13:13:45","modified_gmt":"2020-02-22T17:13:45","slug":"intervalos-de-sexta-para-el-cuatro-venezolano","status":"publish","type":"post","link":"https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/","title":{"rendered":"Intervalos de Sexta para el Cuatro Venezolano"},"content":{"rendered":"<p style=\"text-align: justify\">Los intervalos de sexta son aquellos que se encuentran separados por una distancia de 4 tonos y1 semitono de la nota principal. \u00a0En el cuatro venezolano son muy \u00fatiles venezolanos ya definen la posici\u00f3n donde se encuentra el acorde relativo de la tonalidad.<\/p>\n<p style=\"text-align: justify\"><!--more--><\/p>\n<p style=\"text-align: justify\">Los intervalos de sexta absolutos para las notas naturales, sin tomar en cuenta los sostenidos y s\u00f3lo viendo el aspecto cuantitativo, son los siguientes:<\/p>\n<ul style=\"text-align: justify\">\n<li>Do &#8211; La<\/li>\n<li>Re &#8211; Si<\/li>\n<li>Mi &#8211; Do<\/li>\n<li>Fa &#8211; Re<\/li>\n<li>Sol &#8211; Mi<\/li>\n<li>La &#8211; Fa<\/li>\n<li>Si &#8211; Sol<\/li>\n<\/ul>\n<h2 style=\"text-align: justify\">Intervalo de Sexta Mayor<\/h2>\n<p style=\"text-align: justify\">Los intervalos de Sexta Mayor son aquellos donde se conserva la distancia exacta de 4 tonos y medio de un acorde a otro. \u00a0 Es importante trabajar con cuidado con las notas Fa y Si, ya que representan medio tono cuando se pasa por un intervalo<\/p>\n<div style=\"text-align: justify\">\n<ul>\n<li>Do &#8211; La<\/li>\n<li>Re &#8211; Si<\/li>\n<li>Mi &#8211; Do#<\/li>\n<li>Fa &#8211; Re<\/li>\n<li>Sol &#8211; Mi<\/li>\n<li>La &#8211; Fa#<\/li>\n<li>Si &#8211; Sol#<\/li>\n<\/ul>\n<\/div>\n<p style=\"text-align: justify\">Estos intervalos definen a los acordes relativos que se utilizar\u00e1n para pasar una canci\u00f3n de tonalidad mayor a tonalidad menor. \u00a0Por ejemplo, si nos encontramos tocando en tonalidad de Re mayor, cuando nos pasamos a la sexta de Re, caemos en el Si menor, relativa del Re mayor. \u00a0 Re Mayor y Si menor son tonalidades relativas siempre.<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/tucuatro.com\/camburpinton\/2012\/relativos-de-los-acordes-en-el-cuatro\/\">Aprende sobre los acordes relativos haciendo click aca<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los intervalos de sexta son aquellos que se encuentran separados por una distancia de 4 tonos y1 semitono de la nota principal.  En el cuatro venezolano son muy \u00fatiles venezolanos ya definen la posici\u00f3n donde se encuentra el acorde relativo de la tonalidad.<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","_tucuatro_chord_instrument":""},"categories":[16,2],"tags":[368,230],"class_list":["post-4155","post","type-post","status-publish","format-standard","hentry","category-aprende","category-cuatro","tag-intervalos","tag-principiante-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intervalos de Sexta para el Cuatro Venezolano - CamburPinton<\/title>\n<meta name=\"description\" content=\"Los intervalos de sexta son aquellos que se encuentran separados por una distancia de 4 tonos y1 semitono de la nota principal. En el cuatro venezolano son muy \u00fatiles venezolanos ya definen la posici\u00f3n donde se encuentra el acorde relativo de la tonalidad.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intervalos de Sexta para el Cuatro Venezolano - CamburPinton\" \/>\n<meta property=\"og:description\" content=\"Los intervalos de sexta son aquellos que se encuentran separados por una distancia de 4 tonos y1 semitono de la nota principal. En el cuatro venezolano son muy \u00fatiles venezolanos ya definen la posici\u00f3n donde se encuentra el acorde relativo de la tonalidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/\" \/>\n<meta property=\"og:site_name\" content=\"CamburPinton\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-24T12:51:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-22T17:13:45+00:00\" \/>\n<meta name=\"author\" content=\"Cambur Pinton\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cambur Pinton\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/intervalos-de-sexta-para-el-cuatro-venezolano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/intervalos-de-sexta-para-el-cuatro-venezolano\\\/\"},\"author\":{\"name\":\"Cambur Pinton\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#\\\/schema\\\/person\\\/68ea61a1649e800be7dd6ae72475d1af\"},\"headline\":\"Intervalos de Sexta para el Cuatro Venezolano\",\"datePublished\":\"2012-11-24T12:51:11+00:00\",\"dateModified\":\"2020-02-22T17:13:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/intervalos-de-sexta-para-el-cuatro-venezolano\\\/\"},\"wordCount\":232,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#organization\"},\"keywords\":[\"intervalos\",\"principiante\"],\"articleSection\":[\"Aprender\",\"Cuatro Instrumento Musical\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/intervalos-de-sexta-para-el-cuatro-venezolano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/intervalos-de-sexta-para-el-cuatro-venezolano\\\/\",\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/intervalos-de-sexta-para-el-cuatro-venezolano\\\/\",\"name\":\"Intervalos de Sexta para el Cuatro Venezolano - CamburPinton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#website\"},\"datePublished\":\"2012-11-24T12:51:11+00:00\",\"dateModified\":\"2020-02-22T17:13:45+00:00\",\"description\":\"Los intervalos de sexta son aquellos que se encuentran separados por una distancia de 4 tonos y1 semitono de la nota principal. En el cuatro venezolano son muy \u00fatiles venezolanos ya definen la posici\u00f3n donde se encuentra el acorde relativo de la tonalidad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/intervalos-de-sexta-para-el-cuatro-venezolano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/intervalos-de-sexta-para-el-cuatro-venezolano\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/intervalos-de-sexta-para-el-cuatro-venezolano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intervalos de Sexta para el Cuatro Venezolano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#website\",\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/\",\"name\":\"CamburPinton\",\"description\":\"El blog del Cuatro Venezolano, por TuCuatro\",\"publisher\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#organization\",\"name\":\"CamburPinton\",\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2020\\\/02\\\/fretboard_icon_black-64px.png\",\"contentUrl\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2020\\\/02\\\/fretboard_icon_black-64px.png\",\"width\":64,\"height\":107,\"caption\":\"CamburPinton\"},\"image\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#\\\/schema\\\/person\\\/68ea61a1649e800be7dd6ae72475d1af\",\"name\":\"Cambur Pinton\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lh3.googleusercontent.com\\\/a\\\/AEdFTp4NQMwimY1QASsobdRfn2FegjEgYm4GD7ArdNpX=s96-c?sz=50\",\"url\":\"https:\\\/\\\/lh3.googleusercontent.com\\\/a\\\/AEdFTp4NQMwimY1QASsobdRfn2FegjEgYm4GD7ArdNpX=s96-c?sz=50\",\"contentUrl\":\"https:\\\/\\\/lh3.googleusercontent.com\\\/a\\\/AEdFTp4NQMwimY1QASsobdRfn2FegjEgYm4GD7ArdNpX=s96-c?sz=50\",\"caption\":\"Cambur Pinton\"},\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/author\\\/camburpinton\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intervalos de Sexta para el Cuatro Venezolano - CamburPinton","description":"Los intervalos de sexta son aquellos que se encuentran separados por una distancia de 4 tonos y1 semitono de la nota principal. En el cuatro venezolano son muy \u00fatiles venezolanos ya definen la posici\u00f3n donde se encuentra el acorde relativo de la tonalidad.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/","og_locale":"es_ES","og_type":"article","og_title":"Intervalos de Sexta para el Cuatro Venezolano - CamburPinton","og_description":"Los intervalos de sexta son aquellos que se encuentran separados por una distancia de 4 tonos y1 semitono de la nota principal. En el cuatro venezolano son muy \u00fatiles venezolanos ya definen la posici\u00f3n donde se encuentra el acorde relativo de la tonalidad.","og_url":"https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/","og_site_name":"CamburPinton","article_published_time":"2012-11-24T12:51:11+00:00","article_modified_time":"2020-02-22T17:13:45+00:00","author":"Cambur Pinton","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Cambur Pinton","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/#article","isPartOf":{"@id":"https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/"},"author":{"name":"Cambur Pinton","@id":"https:\/\/tucuatro.com\/camburpinton\/#\/schema\/person\/68ea61a1649e800be7dd6ae72475d1af"},"headline":"Intervalos de Sexta para el Cuatro Venezolano","datePublished":"2012-11-24T12:51:11+00:00","dateModified":"2020-02-22T17:13:45+00:00","mainEntityOfPage":{"@id":"https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/"},"wordCount":232,"commentCount":1,"publisher":{"@id":"https:\/\/tucuatro.com\/camburpinton\/#organization"},"keywords":["intervalos","principiante"],"articleSection":["Aprender","Cuatro Instrumento Musical"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/","url":"https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/","name":"Intervalos de Sexta para el Cuatro Venezolano - CamburPinton","isPartOf":{"@id":"https:\/\/tucuatro.com\/camburpinton\/#website"},"datePublished":"2012-11-24T12:51:11+00:00","dateModified":"2020-02-22T17:13:45+00:00","description":"Los intervalos de sexta son aquellos que se encuentran separados por una distancia de 4 tonos y1 semitono de la nota principal. En el cuatro venezolano son muy \u00fatiles venezolanos ya definen la posici\u00f3n donde se encuentra el acorde relativo de la tonalidad.","breadcrumb":{"@id":"https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tucuatro.com\/camburpinton\/intervalos-de-sexta-para-el-cuatro-venezolano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tucuatro.com\/camburpinton\/"},{"@type":"ListItem","position":2,"name":"Intervalos de Sexta para el Cuatro Venezolano"}]},{"@type":"WebSite","@id":"https:\/\/tucuatro.com\/camburpinton\/#website","url":"https:\/\/tucuatro.com\/camburpinton\/","name":"CamburPinton","description":"El blog del Cuatro Venezolano, por TuCuatro","publisher":{"@id":"https:\/\/tucuatro.com\/camburpinton\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tucuatro.com\/camburpinton\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tucuatro.com\/camburpinton\/#organization","name":"CamburPinton","url":"https:\/\/tucuatro.com\/camburpinton\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tucuatro.com\/camburpinton\/#\/schema\/logo\/image\/","url":"https:\/\/tucuatro.com\/camburpinton\/wp-content\/uploads\/sites\/5\/2020\/02\/fretboard_icon_black-64px.png","contentUrl":"https:\/\/tucuatro.com\/camburpinton\/wp-content\/uploads\/sites\/5\/2020\/02\/fretboard_icon_black-64px.png","width":64,"height":107,"caption":"CamburPinton"},"image":{"@id":"https:\/\/tucuatro.com\/camburpinton\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tucuatro.com\/camburpinton\/#\/schema\/person\/68ea61a1649e800be7dd6ae72475d1af","name":"Cambur Pinton","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lh3.googleusercontent.com\/a\/AEdFTp4NQMwimY1QASsobdRfn2FegjEgYm4GD7ArdNpX=s96-c?sz=50","url":"https:\/\/lh3.googleusercontent.com\/a\/AEdFTp4NQMwimY1QASsobdRfn2FegjEgYm4GD7ArdNpX=s96-c?sz=50","contentUrl":"https:\/\/lh3.googleusercontent.com\/a\/AEdFTp4NQMwimY1QASsobdRfn2FegjEgYm4GD7ArdNpX=s96-c?sz=50","caption":"Cambur Pinton"},"url":"https:\/\/tucuatro.com\/camburpinton\/author\/camburpinton\/"}]}},"_links":{"self":[{"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/posts\/4155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/comments?post=4155"}],"version-history":[{"count":0,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/posts\/4155\/revisions"}],"wp:attachment":[{"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/media?parent=4155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/categories?post=4155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/tags?post=4155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}