{"id":704,"date":"2010-09-08T08:54:21","date_gmt":"2010-09-08T13:24:21","guid":{"rendered":"https:\/\/tucuatro.com\/camburpinton\/?p=704"},"modified":"2020-02-22T14:55:41","modified_gmt":"2020-02-22T18:55:41","slug":"clase-de-ritmo-de-gaita","status":"publish","type":"post","link":"https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/","title":{"rendered":"Clase de Ritmo de Gaita"},"content":{"rendered":"<p style=\"text-align: justify\">Cuando se acerca la \u00e9poca decembrina es momento de ir practicando las gaitas que tocaremos en las parrandas familiares. \u00a0Si a\u00fan no te has aprendido este sabroso ritmo, es momento que lo hagas. \u00a0Te invitamos a aprender y practicar con un video de Pedro Borrero que te explicar\u00e1 con detalle c\u00f3mo tocar este ritmo maracucho:<!--more--><\/p>\n<p style=\"text-align: center\"><strong>CLASE DE RITMO DE GAITA<\/strong><br \/>\nPedro Borrero<\/p>\n<p style=\"text-align: center\"><a href=\"http:\/\/www.youtube.com\/watch?v=AoJdrA5CoRA\">http:\/\/www.youtube.com\/watch?v=AoJdrA5CoRA<\/a><\/p>\n<p style=\"text-align: justify\">Aprende par de canciones y podr\u00e1s disfrutar en familia durante las \u00e9pocas decembrinas tocando el cuatro en cada reuni\u00f3n familiar.<\/p>\n<p style=\"text-align: justify\">Si quieres recibir m\u00e1s clases de cuatro y m\u00e1s noticias acerca de toda la movida del cuatro venezolano, suscribete al blog ahora:<\/p>\n<div class=\"alertorange\"><span class=\"wpr-subform-hidden-fields\"><\/p>\n<p><\/span><\/p>\n<table class=\"aligncenter\">\n<tbody>\n<tr>\n<td><span class=\"wprsfl wprsfl-name\">Nombre:<\/span><\/td>\n<td><span class=\"wprsftf wpr-subform-textfield-name\"><br \/>\n<\/span><\/td>\n<\/tr>\n<tr>\n<td><span class=\"wprsfl wprsfl-email\">E-Mail:<\/span><\/td>\n<td><span class=\"wprsftf wpsftf-email\"><\/p>\n<p><\/span><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" align=\"center\"><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\" align=\"center\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: justify\">Cuando se acerca la \u00e9poca decembrina es momento de ir practicando las gaitas que tocaremos en las parrandas familiares. \u00a0Si a\u00fan no te has aprendido este sabroso ritmo, es momento que lo hagas. \u00a0Te invitamos a aprender y practicar con un video de Pedro Borrero que te explicar\u00e1 con detalle c\u00f3mo tocar este<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":"","_tucuatro_chord_instrument":""},"categories":[16],"tags":[118,75,52],"class_list":["post-704","post","type-post","status-publish","format-standard","hentry","category-aprende","tag-gaita","tag-pedro-borrero-2","tag-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Clase de Ritmo de Gaita - CamburPinton<\/title>\n<meta name=\"description\" content=\"Cuando se acerca la \u00e9poca decembrina es momento de ir practicando las gaitas que tocaremos en las parrandas familiares. \u00a0Si a\u00fan no te has aprendido este sabroso ritmo, es momento que lo hagas. \u00a0Te invitamos a aprender y practicar con un video de Pedro Borrero que te explicar\u00e1 con detalle c\u00f3mo tocar este\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clase de Ritmo de Gaita - CamburPinton\" \/>\n<meta property=\"og:description\" content=\"Cuando se acerca la \u00e9poca decembrina es momento de ir practicando las gaitas que tocaremos en las parrandas familiares. \u00a0Si a\u00fan no te has aprendido este sabroso ritmo, es momento que lo hagas. \u00a0Te invitamos a aprender y practicar con un video de Pedro Borrero que te explicar\u00e1 con detalle c\u00f3mo tocar este\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/\" \/>\n<meta property=\"og:site_name\" content=\"CamburPinton\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-08T13:24:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-22T18:55:41+00:00\" \/>\n<meta name=\"author\" content=\"Adrian Toro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adrian Toro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/clase-de-ritmo-de-gaita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/clase-de-ritmo-de-gaita\\\/\"},\"author\":{\"name\":\"Adrian Toro\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#\\\/schema\\\/person\\\/182f36d7f076c0e15716be890bb6d074\"},\"headline\":\"Clase de Ritmo de Gaita\",\"datePublished\":\"2010-09-08T13:24:21+00:00\",\"dateModified\":\"2020-02-22T18:55:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/clase-de-ritmo-de-gaita\\\/\"},\"wordCount\":125,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#organization\"},\"keywords\":[\"gaita\",\"pedro borrero\",\"video\"],\"articleSection\":[\"Aprender\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/clase-de-ritmo-de-gaita\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/clase-de-ritmo-de-gaita\\\/\",\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/clase-de-ritmo-de-gaita\\\/\",\"name\":\"Clase de Ritmo de Gaita - CamburPinton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#website\"},\"datePublished\":\"2010-09-08T13:24:21+00:00\",\"dateModified\":\"2020-02-22T18:55:41+00:00\",\"description\":\"Cuando se acerca la \u00e9poca decembrina es momento de ir practicando las gaitas que tocaremos en las parrandas familiares. \u00a0Si a\u00fan no te has aprendido este sabroso ritmo, es momento que lo hagas. \u00a0Te invitamos a aprender y practicar con un video de Pedro Borrero que te explicar\u00e1 con detalle c\u00f3mo tocar este\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/clase-de-ritmo-de-gaita\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/clase-de-ritmo-de-gaita\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/clase-de-ritmo-de-gaita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clase de Ritmo de Gaita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#website\",\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/\",\"name\":\"CamburPinton\",\"description\":\"El blog del Cuatro Venezolano, por TuCuatro\",\"publisher\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#organization\",\"name\":\"CamburPinton\",\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2020\\\/02\\\/fretboard_icon_black-64px.png\",\"contentUrl\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2020\\\/02\\\/fretboard_icon_black-64px.png\",\"width\":64,\"height\":107,\"caption\":\"CamburPinton\"},\"image\":{\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/#\\\/schema\\\/person\\\/182f36d7f076c0e15716be890bb6d074\",\"name\":\"Adrian Toro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lh3.googleusercontent.com\\\/a\\\/ACg8ocLwLCmGuaPjDUjycH1soWxJ2CWxtdwwxTMhw7SjMADBmZbcikz5ww=s96-c?sz=50\",\"url\":\"https:\\\/\\\/lh3.googleusercontent.com\\\/a\\\/ACg8ocLwLCmGuaPjDUjycH1soWxJ2CWxtdwwxTMhw7SjMADBmZbcikz5ww=s96-c?sz=50\",\"contentUrl\":\"https:\\\/\\\/lh3.googleusercontent.com\\\/a\\\/ACg8ocLwLCmGuaPjDUjycH1soWxJ2CWxtdwwxTMhw7SjMADBmZbcikz5ww=s96-c?sz=50\",\"caption\":\"Adrian Toro\"},\"description\":\"Adri\u00e1n Toro es el fundador de TuCuatro Corp., una empresa dedicada a la difusi\u00f3n y ense\u00f1anza de instrumentos folkl\u00f3ricos, con un enfoque especial en el cuatro venezolano. Apasionado por la m\u00fasica y la educaci\u00f3n, ha trabajado durante a\u00f1os para conectar a m\u00fasicos, estudiantes y aficionados con recursos innovadores para aprender y perfeccionar su t\u00e9cnica. Bajo su liderazgo, TuCuatro se ha convertido en una plataforma de referencia internacional, promoviendo la riqueza cultural de los instrumentos de cuerda ex\u00f3ticos. Su misi\u00f3n es garantizar que estas tradiciones musicales sigan vivas y accesibles para futuras generaciones.\",\"sameAs\":[\"https:\\\/\\\/tucuatro.com\"],\"url\":\"https:\\\/\\\/tucuatro.com\\\/camburpinton\\\/author\\\/adrianifero\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clase de Ritmo de Gaita - CamburPinton","description":"Cuando se acerca la \u00e9poca decembrina es momento de ir practicando las gaitas que tocaremos en las parrandas familiares. \u00a0Si a\u00fan no te has aprendido este sabroso ritmo, es momento que lo hagas. \u00a0Te invitamos a aprender y practicar con un video de Pedro Borrero que te explicar\u00e1 con detalle c\u00f3mo tocar este","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/","og_locale":"es_ES","og_type":"article","og_title":"Clase de Ritmo de Gaita - CamburPinton","og_description":"Cuando se acerca la \u00e9poca decembrina es momento de ir practicando las gaitas que tocaremos en las parrandas familiares. \u00a0Si a\u00fan no te has aprendido este sabroso ritmo, es momento que lo hagas. \u00a0Te invitamos a aprender y practicar con un video de Pedro Borrero que te explicar\u00e1 con detalle c\u00f3mo tocar este","og_url":"https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/","og_site_name":"CamburPinton","article_published_time":"2010-09-08T13:24:21+00:00","article_modified_time":"2020-02-22T18:55:41+00:00","author":"Adrian Toro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Adrian Toro","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/#article","isPartOf":{"@id":"https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/"},"author":{"name":"Adrian Toro","@id":"https:\/\/tucuatro.com\/camburpinton\/#\/schema\/person\/182f36d7f076c0e15716be890bb6d074"},"headline":"Clase de Ritmo de Gaita","datePublished":"2010-09-08T13:24:21+00:00","dateModified":"2020-02-22T18:55:41+00:00","mainEntityOfPage":{"@id":"https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/"},"wordCount":125,"commentCount":3,"publisher":{"@id":"https:\/\/tucuatro.com\/camburpinton\/#organization"},"keywords":["gaita","pedro borrero","video"],"articleSection":["Aprender"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/","url":"https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/","name":"Clase de Ritmo de Gaita - CamburPinton","isPartOf":{"@id":"https:\/\/tucuatro.com\/camburpinton\/#website"},"datePublished":"2010-09-08T13:24:21+00:00","dateModified":"2020-02-22T18:55:41+00:00","description":"Cuando se acerca la \u00e9poca decembrina es momento de ir practicando las gaitas que tocaremos en las parrandas familiares. \u00a0Si a\u00fan no te has aprendido este sabroso ritmo, es momento que lo hagas. \u00a0Te invitamos a aprender y practicar con un video de Pedro Borrero que te explicar\u00e1 con detalle c\u00f3mo tocar este","breadcrumb":{"@id":"https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tucuatro.com\/camburpinton\/clase-de-ritmo-de-gaita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tucuatro.com\/camburpinton\/"},{"@type":"ListItem","position":2,"name":"Clase de Ritmo de Gaita"}]},{"@type":"WebSite","@id":"https:\/\/tucuatro.com\/camburpinton\/#website","url":"https:\/\/tucuatro.com\/camburpinton\/","name":"CamburPinton","description":"El blog del Cuatro Venezolano, por TuCuatro","publisher":{"@id":"https:\/\/tucuatro.com\/camburpinton\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tucuatro.com\/camburpinton\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tucuatro.com\/camburpinton\/#organization","name":"CamburPinton","url":"https:\/\/tucuatro.com\/camburpinton\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tucuatro.com\/camburpinton\/#\/schema\/logo\/image\/","url":"https:\/\/tucuatro.com\/camburpinton\/wp-content\/uploads\/sites\/5\/2020\/02\/fretboard_icon_black-64px.png","contentUrl":"https:\/\/tucuatro.com\/camburpinton\/wp-content\/uploads\/sites\/5\/2020\/02\/fretboard_icon_black-64px.png","width":64,"height":107,"caption":"CamburPinton"},"image":{"@id":"https:\/\/tucuatro.com\/camburpinton\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tucuatro.com\/camburpinton\/#\/schema\/person\/182f36d7f076c0e15716be890bb6d074","name":"Adrian Toro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLwLCmGuaPjDUjycH1soWxJ2CWxtdwwxTMhw7SjMADBmZbcikz5ww=s96-c?sz=50","url":"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLwLCmGuaPjDUjycH1soWxJ2CWxtdwwxTMhw7SjMADBmZbcikz5ww=s96-c?sz=50","contentUrl":"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLwLCmGuaPjDUjycH1soWxJ2CWxtdwwxTMhw7SjMADBmZbcikz5ww=s96-c?sz=50","caption":"Adrian Toro"},"description":"Adri\u00e1n Toro es el fundador de TuCuatro Corp., una empresa dedicada a la difusi\u00f3n y ense\u00f1anza de instrumentos folkl\u00f3ricos, con un enfoque especial en el cuatro venezolano. Apasionado por la m\u00fasica y la educaci\u00f3n, ha trabajado durante a\u00f1os para conectar a m\u00fasicos, estudiantes y aficionados con recursos innovadores para aprender y perfeccionar su t\u00e9cnica. Bajo su liderazgo, TuCuatro se ha convertido en una plataforma de referencia internacional, promoviendo la riqueza cultural de los instrumentos de cuerda ex\u00f3ticos. Su misi\u00f3n es garantizar que estas tradiciones musicales sigan vivas y accesibles para futuras generaciones.","sameAs":["https:\/\/tucuatro.com"],"url":"https:\/\/tucuatro.com\/camburpinton\/author\/adrianifero\/"}]}},"_links":{"self":[{"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/posts\/704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/comments?post=704"}],"version-history":[{"count":0,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/posts\/704\/revisions"}],"wp:attachment":[{"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/media?parent=704"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/categories?post=704"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tucuatro.com\/camburpinton\/wp-json\/wp\/v2\/tags?post=704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}